{"id":4073,"date":"2019-07-25T17:20:40","date_gmt":"2019-07-25T15:20:40","guid":{"rendered":"https:\/\/www.asssa.es\/ca\/?page_id=4073"},"modified":"2025-09-16T15:48:33","modified_gmt":"2025-09-16T13:48:33","slug":"els-nostres-compromisos","status":"publish","type":"page","link":"https:\/\/www.asssa.es\/ca\/sobre-asssa\/els-nostres-compromisos\/","title":{"rendered":"ELS NOSTRES COMPROMISOS"},"content":{"rendered":"<h2>Estem compromesos<\/h2>\n<p>La salut \u00e9s la nostra ra\u00f3 de ser, d\u2019aqu\u00ed la nostra forta vinculaci\u00f3 amb el benestar de la societat i la cura del medi ambient.<\/p>\n<p>&nbsp;<\/p>\n<p>Adquirim diversos compromisos i els portem a terme mitjan\u00e7ant la nostra col\u00b7laboraci\u00f3 en diferents accions socials, aportant el nostre granet de sorra per millorar l\u2019entorn que ens envolta.<\/p>\n<p>&nbsp;<\/p>\n<p>Empatitzem amb la societat i ens esforcem en desenvolupar un pla de Responsabilitat Social Corporativa que contribueix a aconseguir un m\u00f3n m\u00e9s just i equilibrat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estem compromesos La salut \u00e9s la nostra ra\u00f3 de ser, d\u2019aqu\u00ed la nostra forta vinculaci\u00f3 amb el benestar de la societat i la cura del medi ambient. &nbsp; Adquirim diversos compromisos i els portem a terme mitjan\u00e7ant la nostra col\u00b7laboraci\u00f3 en diferents accions socials, aportant el nostre granet de sorra per millorar l\u2019entorn que ens [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":13105,"parent":14,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"tpl-compromisos.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4073","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ELS NOSTRES COMPROMISOS - ASSSA Catal\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asssa.es\/ca\/sobre-asssa\/els-nostres-compromisos\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ELS NOSTRES COMPROMISOS - ASSSA Catal\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Estem compromesos La salut \u00e9s la nostra ra\u00f3 de ser, d\u2019aqu\u00ed la nostra forta vinculaci\u00f3 amb el benestar de la societat i la cura del medi ambient. &nbsp; Adquirim diversos compromisos i els portem a terme mitjan\u00e7ant la nostra col\u00b7laboraci\u00f3 en diferents accions socials, aportant el nostre granet de sorra per millorar l\u2019entorn que ens [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asssa.es\/ca\/sobre-asssa\/els-nostres-compromisos\/\" \/>\n<meta property=\"og:site_name\" content=\"ASSSA Catal\u00e1n\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T13:48:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asssa.es\/wp-content\/uploads\/2025\/09\/Sobre-ASSSA-Compromisos-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/ca\\\/sobre-asssa\\\/els-nostres-compromisos\\\/\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/ca\\\/sobre-asssa\\\/els-nostres-compromisos\\\/\",\"name\":\"ELS NOSTRES COMPROMISOS - ASSSA Catal\u00e1n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/ca\\\/sobre-asssa\\\/els-nostres-compromisos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/ca\\\/sobre-asssa\\\/els-nostres-compromisos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Sobre-ASSSA-Compromisos-5.png\",\"datePublished\":\"2019-07-25T15:20:40+00:00\",\"dateModified\":\"2025-09-16T13:48:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/ca\\\/sobre-asssa\\\/els-nostres-compromisos\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asssa.es\\\/ca\\\/sobre-asssa\\\/els-nostres-compromisos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/ca\\\/sobre-asssa\\\/els-nostres-compromisos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Sobre-ASSSA-Compromisos-5.png\",\"contentUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Sobre-ASSSA-Compromisos-5.png\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/ca\\\/sobre-asssa\\\/els-nostres-compromisos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.asssa.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobre ASSSA\",\"item\":\"https:\\\/\\\/www.asssa.es\\\/ca\\\/sobre-asssa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ELS NOSTRES COMPROMISOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/ca\\\/\",\"name\":\"ASSSA Catal\u00e1n\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asssa.es\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ELS NOSTRES COMPROMISOS - ASSSA Catal\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asssa.es\/ca\/sobre-asssa\/els-nostres-compromisos\/","og_locale":"ca_ES","og_type":"article","og_title":"ELS NOSTRES COMPROMISOS - ASSSA Catal\u00e1n","og_description":"Estem compromesos La salut \u00e9s la nostra ra\u00f3 de ser, d\u2019aqu\u00ed la nostra forta vinculaci\u00f3 amb el benestar de la societat i la cura del medi ambient. &nbsp; Adquirim diversos compromisos i els portem a terme mitjan\u00e7ant la nostra col\u00b7laboraci\u00f3 en diferents accions socials, aportant el nostre granet de sorra per millorar l\u2019entorn que ens [&hellip;]","og_url":"https:\/\/www.asssa.es\/ca\/sobre-asssa\/els-nostres-compromisos\/","og_site_name":"ASSSA Catal\u00e1n","article_modified_time":"2025-09-16T13:48:33+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2025\/09\/Sobre-ASSSA-Compromisos-5.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asssa.es\/ca\/sobre-asssa\/els-nostres-compromisos\/","url":"https:\/\/www.asssa.es\/ca\/sobre-asssa\/els-nostres-compromisos\/","name":"ELS NOSTRES COMPROMISOS - ASSSA Catal\u00e1n","isPartOf":{"@id":"https:\/\/www.asssa.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asssa.es\/ca\/sobre-asssa\/els-nostres-compromisos\/#primaryimage"},"image":{"@id":"https:\/\/www.asssa.es\/ca\/sobre-asssa\/els-nostres-compromisos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2025\/09\/Sobre-ASSSA-Compromisos-5.png","datePublished":"2019-07-25T15:20:40+00:00","dateModified":"2025-09-16T13:48:33+00:00","breadcrumb":{"@id":"https:\/\/www.asssa.es\/ca\/sobre-asssa\/els-nostres-compromisos\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asssa.es\/ca\/sobre-asssa\/els-nostres-compromisos\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.asssa.es\/ca\/sobre-asssa\/els-nostres-compromisos\/#primaryimage","url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2025\/09\/Sobre-ASSSA-Compromisos-5.png","contentUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2025\/09\/Sobre-ASSSA-Compromisos-5.png","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.asssa.es\/ca\/sobre-asssa\/els-nostres-compromisos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asssa.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Sobre ASSSA","item":"https:\/\/www.asssa.es\/ca\/sobre-asssa\/"},{"@type":"ListItem","position":3,"name":"ELS NOSTRES COMPROMISOS"}]},{"@type":"WebSite","@id":"https:\/\/www.asssa.es\/ca\/#website","url":"https:\/\/www.asssa.es\/ca\/","name":"ASSSA Catal\u00e1n","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asssa.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/www.asssa.es\/ca\/wp-json\/wp\/v2\/pages\/4073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asssa.es\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.asssa.es\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/ca\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/ca\/wp-json\/wp\/v2\/comments?post=4073"}],"version-history":[{"count":5,"href":"https:\/\/www.asssa.es\/ca\/wp-json\/wp\/v2\/pages\/4073\/revisions"}],"predecessor-version":[{"id":9051,"href":"https:\/\/www.asssa.es\/ca\/wp-json\/wp\/v2\/pages\/4073\/revisions\/9051"}],"up":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/ca\/wp-json\/wp\/v2\/pages\/14"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/ca\/wp-json\/wp\/v2\/media\/13105"}],"wp:attachment":[{"href":"https:\/\/www.asssa.es\/ca\/wp-json\/wp\/v2\/media?parent=4073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}