{"id":13709,"date":"2023-10-10T15:52:24","date_gmt":"2023-10-10T13:52:24","guid":{"rendered":"https:\/\/www.asssa.es\/de\/?p=13709"},"modified":"2023-10-10T15:56:04","modified_gmt":"2023-10-10T13:56:04","slug":"frau-doktor-habe-ich-eine-zwangsstoerung","status":"publish","type":"post","link":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/","title":{"rendered":"\u201eFrau Doktor, habe ich eine Zwangsst\u00f6rung?\u201c"},"content":{"rendered":"<p>\u201eFrau Doktor, ich brauche Hilfe. Ich glaube, ich habe eine Zwangsst\u00f6rung, weil ich sehr manisch bin, ein Perfektionist, B\u00fccher in alphabetischer Reihenfolge ordne und offene Schrankt\u00fcren nicht ausstehen kann\u201c. Wenn Sie sich in einer dieser Aussagen wiedererkennen, hei\u00dft das aber noch lange nicht, dass Sie an einer Zwangsst\u00f6rung leiden.<\/p>\n<p><!--more--><\/p>\n<p>Die Zwangsst\u00f6rung ist eine der f\u00fcnf h\u00e4ufigsten psychischen Erkrankungen, die allerdings nur 1 % der Bev\u00f6lkerung betrifft. Sie geh\u00f6rt zu den Angstst\u00f6rungen und kann in der Regel in zwei Lebensabschnitten auftreten, in der Jugend oder im jungen Erwachsenenalter.<\/p>\n<p>Sie umfasst Zwangsgedanken, die besonders gro\u00dfe Angst und den Drang zur Bek\u00e4mpfung dieser Gedanken ausl\u00f6sen, wodurch Zwangshandlungen entwickelt werden. Der Schweregrad h\u00e4ngt davon ab, wie sehr die Person davon beeintr\u00e4chtigt wird, und verschlimmert sich in der Regel in Stresssituationen. Der Kreislauf aus Zwangsgedanken und -handlungen dauert oft so lange an, dass wichtige Aktivit\u00e4ten unterbrochen werden, was sich auf das normale Leben der betroffenen Person auswirkt.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Zwangsgedanken<\/strong><\/p>\n<p>Dabei handelt es sich um<strong> wiederkehrende, unfreiwillige und irrationale Gedanken oder Bilder, <\/strong>die Angst, Kummer und Beklemmung verursachen. Patienten beschreiben sie oft als \u201eeinen Gedanken, den jemand in ihren Kopf einpflanzt\u201c. Zu den h\u00e4ufigsten geh\u00f6ren:<\/p>\n<ul>\n<li>Angst vor Ansteckung oder Schmutz. Zum Beispiel die Angst, sich durch das Ber\u00fchren von Gegenst\u00e4nden, die bereits von anderen ber\u00fchrt wurden, anzustecken<\/li>\n<li>Zweifel und Schwierigkeiten, Ungewissheit zu akzeptieren (\u201eHabe ich die T\u00fcr abgeschlossen? Habe ich den Herd ausgemacht?\u201d)<\/li>\n<li>Extremer Drang, Dinge ordentlich und symmetrisch zu halten<\/li>\n<li>Angst, die Kontrolle zu verlieren und sich oder andere zu verletzen. Zum Beispiel das \u00dcberholen eines Radfahrers mit dem Auto und die Angst, ihn \u00fcberfahren zu haben<\/li>\n<li>Unerw\u00fcnschte sexuelle Gedanken<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Zwangshandlungen<\/strong><\/p>\n<p>Hierbei handelt es sich um Verhaltensweisen, die wiederholt werden, <strong>um so die durch die Zwangsgedanken verursachten Leiden zu neutralisieren<\/strong>. Oft ist mit der Zwangshandlung auch das sogenannte magische Denken verbunden: \u201eWenn ich das nicht tue, k\u00f6nnte etwas Schlimmes passieren\u201c. In jedem Fall bereiten die Zwangshandlungen keine Freude und verschaffen nur vor\u00fcbergehend Erleichterung. Zu den h\u00e4ufigsten geh\u00f6ren:<\/p>\n<ul>\n<li>Putzen und Waschen, z. B. exzessives H\u00e4ndewaschen, bis es zu Verletzungen kommt<\/li>\n<li>Kontrollieren: Beharrliches und wiederholtes \u00dcberpr\u00fcfen, ob eine Aufgabe erledigt wurde<\/li>\n<li>Ordnen: Gegenst\u00e4nde in einer bestimmten Reihenfolge anordnen<\/li>\n<li>Wiederholen einer bestimmten Anzahl von W\u00f6rtern, S\u00e4tzen oder Handlungen<\/li>\n<li>Z\u00e4hlen nach bestimmten Mustern<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Behandlung<\/strong><\/p>\n<p>Zun\u00e4chst sollte ein <strong>Spezialist<\/strong> aufgesucht werden, <strong>der<\/strong> <strong>eine Diagnose stellt und den Verlauf der Erkrankung verfolgt<\/strong>. Die besten Ergebnisse hat bisher die kognitive Verhaltenstherapie erzielt, die je nach Schweregrad und Beeintr\u00e4chtigung mit oder ohne Medikamente durchgef\u00fchrt wird.<\/p>\n<p>Unter den medikament\u00f6sen Behandlungen, die immer von \u00c4rzten verschrieben werden, sind vor allem Antidepressiva \u00fcblich, meist in h\u00f6herer Dosierung als bei anderen St\u00f6rungen. Bis die Behandlung anschl\u00e4gt oder auch um ihre Wirkung zu optimieren, wird sie h\u00e4ufig mit Angstl\u00f6sern kombiniert. Mit der richtigen Behandlung kann die Zwangsst\u00f6rung geheilt und ein besserer Lebensstandard sowie ein angenehmes Alltagsleben erreicht werden.<\/p>\n<p style=\"text-align: right;\">Dr. Patricia Herbera<\/p>\n<p style=\"text-align: right;\">Facharzt f\u00fcr Psychiatrie an der Uniklinik Hospital Universitario San Juan de Alicante<\/p>\n<h6><strong><u><a href=\"https:\/\/www.asssa.es\/de\/versicherung\/krankenversicherungen-\/\" target=\"_blank\" rel=\"noopener noreferrer\">Medizinische Leistungen ASSSA<\/a><\/u><\/strong><\/h6>\n<h6><em>Die ver\u00f6ffentlichte Information ersetzt in keinster Weise die direkte Konsultation mit einem Arzt, weder seine Diagnose noch den verschriebenen Behandlungsplan. Bitte auch nocht als Selbstdiagnoseverfahren verwenden.\u00a0<\/em><\/h6>\n<h6><em>Der Leser nutzt diesen Service in ausschliesslich eigener Verantwortung.\u00a0<\/em><\/h6>\n<h6><em>ASSSA empfiehlt, bei Fragen und Zweifeln sich zun\u00e4chst direkt an Ihren Arzt zu wenden.<\/em><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>\u201eFrau Doktor, ich brauche Hilfe. Ich glaube, ich habe eine Zwangsst\u00f6rung, weil ich sehr manisch bin, ein Perfektionist, B\u00fccher in alphabetischer Reihenfolge ordne und offene Schrankt\u00fcren nicht ausstehen kann\u201c. Wenn Sie sich in einer dieser Aussagen wiedererkennen, hei\u00dft das aber noch lange nicht, dass Sie an einer Zwangsst\u00f6rung leiden.<\/p>\n","protected":false},"author":17,"featured_media":13786,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-13709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesundheit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201eFrau Doktor, habe ich eine Zwangsst\u00f6rung?\u201c - ASSSA Deutsch<\/title>\n<meta name=\"description\" content=\"Die Zwangsst\u00f6rung ist eine der f\u00fcnf h\u00e4ufigsten psychischen Erkrankungen, die allerdings nur 1 % der Bev\u00f6lkerung betrifft.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201eFrau Doktor, habe ich eine Zwangsst\u00f6rung?\u201c - ASSSA Deutsch\" \/>\n<meta property=\"og:description\" content=\"Die Zwangsst\u00f6rung ist eine der f\u00fcnf h\u00e4ufigsten psychischen Erkrankungen, die allerdings nur 1 % der Bev\u00f6lkerung betrifft.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/\" \/>\n<meta property=\"og:site_name\" content=\"ASSSA Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T13:52:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-10T13:56:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/10\/imagen-blog-TOC-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"297\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"anabisquert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"anabisquert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/frau-doktor-habe-ich-eine-zwangsstoerung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/frau-doktor-habe-ich-eine-zwangsstoerung\\\/\"},\"author\":{\"name\":\"anabisquert\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\"},\"headline\":\"\u201eFrau Doktor, habe ich eine Zwangsst\u00f6rung?\u201c\",\"datePublished\":\"2023-10-10T13:52:24+00:00\",\"dateModified\":\"2023-10-10T13:56:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/frau-doktor-habe-ich-eine-zwangsstoerung\\\/\"},\"wordCount\":581,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/frau-doktor-habe-ich-eine-zwangsstoerung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/imagen-blog-TOC-2.png\",\"articleSection\":[\"Gesundheit\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/frau-doktor-habe-ich-eine-zwangsstoerung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/frau-doktor-habe-ich-eine-zwangsstoerung\\\/\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/frau-doktor-habe-ich-eine-zwangsstoerung\\\/\",\"name\":\"\u201eFrau Doktor, habe ich eine Zwangsst\u00f6rung?\u201c - ASSSA Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/frau-doktor-habe-ich-eine-zwangsstoerung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/frau-doktor-habe-ich-eine-zwangsstoerung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/imagen-blog-TOC-2.png\",\"datePublished\":\"2023-10-10T13:52:24+00:00\",\"dateModified\":\"2023-10-10T13:56:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\"},\"description\":\"Die Zwangsst\u00f6rung ist eine der f\u00fcnf h\u00e4ufigsten psychischen Erkrankungen, die allerdings nur 1 % der Bev\u00f6lkerung betrifft.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/frau-doktor-habe-ich-eine-zwangsstoerung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/frau-doktor-habe-ich-eine-zwangsstoerung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/frau-doktor-habe-ich-eine-zwangsstoerung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/imagen-blog-TOC-2.png\",\"contentUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/imagen-blog-TOC-2.png\",\"width\":600,\"height\":297,\"caption\":\"Zwangsst\u00f6rung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/frau-doktor-habe-ich-eine-zwangsstoerung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201eFrau Doktor, habe ich eine Zwangsst\u00f6rung?\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/\",\"name\":\"ASSSA Deutsch\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\",\"name\":\"anabisquert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"caption\":\"anabisquert\"},\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/author\\\/anabisquert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201eFrau Doktor, habe ich eine Zwangsst\u00f6rung?\u201c - ASSSA Deutsch","description":"Die Zwangsst\u00f6rung ist eine der f\u00fcnf h\u00e4ufigsten psychischen Erkrankungen, die allerdings nur 1 % der Bev\u00f6lkerung betrifft.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/","og_locale":"de_DE","og_type":"article","og_title":"\u201eFrau Doktor, habe ich eine Zwangsst\u00f6rung?\u201c - ASSSA Deutsch","og_description":"Die Zwangsst\u00f6rung ist eine der f\u00fcnf h\u00e4ufigsten psychischen Erkrankungen, die allerdings nur 1 % der Bev\u00f6lkerung betrifft.","og_url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/","og_site_name":"ASSSA Deutsch","article_published_time":"2023-10-10T13:52:24+00:00","article_modified_time":"2023-10-10T13:56:04+00:00","og_image":[{"width":600,"height":297,"url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/10\/imagen-blog-TOC-2.png","type":"image\/png"}],"author":"anabisquert","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"anabisquert","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/#article","isPartOf":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/"},"author":{"name":"anabisquert","@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606"},"headline":"\u201eFrau Doktor, habe ich eine Zwangsst\u00f6rung?\u201c","datePublished":"2023-10-10T13:52:24+00:00","dateModified":"2023-10-10T13:56:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/"},"wordCount":581,"commentCount":0,"image":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/10\/imagen-blog-TOC-2.png","articleSection":["Gesundheit"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/","url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/","name":"\u201eFrau Doktor, habe ich eine Zwangsst\u00f6rung?\u201c - ASSSA Deutsch","isPartOf":{"@id":"https:\/\/www.asssa.es\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/#primaryimage"},"image":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/10\/imagen-blog-TOC-2.png","datePublished":"2023-10-10T13:52:24+00:00","dateModified":"2023-10-10T13:56:04+00:00","author":{"@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606"},"description":"Die Zwangsst\u00f6rung ist eine der f\u00fcnf h\u00e4ufigsten psychischen Erkrankungen, die allerdings nur 1 % der Bev\u00f6lkerung betrifft.","breadcrumb":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/#primaryimage","url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/10\/imagen-blog-TOC-2.png","contentUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/10\/imagen-blog-TOC-2.png","width":600,"height":297,"caption":"Zwangsst\u00f6rung"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/frau-doktor-habe-ich-eine-zwangsstoerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asssa.es\/de\/"},{"@type":"ListItem","position":2,"name":"\u201eFrau Doktor, habe ich eine Zwangsst\u00f6rung?\u201c"}]},{"@type":"WebSite","@id":"https:\/\/www.asssa.es\/de\/#website","url":"https:\/\/www.asssa.es\/de\/","name":"ASSSA Deutsch","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asssa.es\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606","name":"anabisquert","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","caption":"anabisquert"},"url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/author\/anabisquert\/"}]}},"jetpack_featured_media_url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/10\/imagen-blog-TOC-2.png","_links":{"self":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/13709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/comments?post=13709"}],"version-history":[{"count":2,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/13709\/revisions"}],"predecessor-version":[{"id":13790,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/13709\/revisions\/13790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/media\/13786"}],"wp:attachment":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/media?parent=13709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/categories?post=13709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/tags?post=13709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}