{"id":14136,"date":"2023-11-22T08:44:33","date_gmt":"2023-11-22T07:44:33","guid":{"rendered":"https:\/\/www.asssa.es\/de\/?p=14136"},"modified":"2023-11-22T08:44:33","modified_gmt":"2023-11-22T07:44:33","slug":"antibiotikaresistenz","status":"publish","type":"post","link":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/","title":{"rendered":"Antibiotikaresistenz"},"content":{"rendered":"<p>Antibiotika sind Medikamente, die zur Bek\u00e4mpfung bakterieller Infektionen eingesetzt werden. Wenn sie korrekt angewendet werden, k\u00f6nnen sie heilen und Leben retten. Wir begegnen jedoch Tag f\u00fcr Tag auch auf Probleme aufgrund resistenter Erreger. Jedes Mal, wenn wir ein Antibiotikum einnehmen, besteht die Gefahr, dass die Bakterien resistent werden, und diese Entwicklung ist progressiv und unaufhaltsam.<\/p>\n<p><!--more--><\/p>\n<p>Was aber bedeutet Antibiotikaresistenz? Sie tritt auf, wenn Bakterien als Reaktion auf die Einnahme dieser Medikamente mutieren. Es sind also nicht Menschen oder Tiere, die gegen Antibiotika resistent werden, sondern Bakterien. Dies wird durch Ver\u00e4nderungen im Erbgut, sogenannten Mutationen, und die \u00dcbertragung von genetischem Material aus anderen Bakterien verursacht.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pr\u00e4vention \u2013 der Schl\u00fcssel zur Eind\u00e4mmung des Problems<\/strong><\/p>\n<p>Wie immer in der Medizin m\u00fcssen wir durch Pr\u00e4vention versuchen, das Problem zu bek\u00e4mpfen. Daf\u00fcr m\u00fcssen wir dem Medikament, also dem Antibiotikum, besondere Aufmerksamkeit widmen, um seine therapeutische Wirkung zu nutzen und die Risiken und Nebenwirkungen seiner Formulierung und Wirkung zu minimieren. <strong>Antibiotika sollten nur dann verschrieben werden, wenn sie nach den geltenden medizinischen Leitlinien erforderlich sind, und antibiotikaresistente Infektionen sollten gemeldet werden.<\/strong><\/p>\n<p>Im Tagesablauf und im Rahmen der \u00e4rztlichen Verschreibung dieses Arzneimittels sollten bestimmte Ma\u00dfnahmen ergriffen werden:<\/p>\n<ul>\n<li>Bei der Einnahme von Antibiotika sollte man sich strikt an die Anweisungen des Arztes halten und sich nicht von unzuverl\u00e4ssigen Quellen wie sozialen Netzwerken, Websites oder nicht\u00e4rztlichen Fachleuten verunsichern lassen.<\/li>\n<li>Antibiotika sollten nur bei bakteriellen Infektionen eingesetzt werden, nicht aber bei viralen Infektionen bzw. aufgrund anderer Ursachen oder Erregern.<\/li>\n<li>Es muss streng auf die Dosierung des Produkts geachtet und die verschriebene Menge bei jeder Einnahme \u00fcber den angegebenen Zeitraum eingehalten werden.<\/li>\n<li>Die Einnahmeanweisungen m\u00fcssen eingehalten werden: ob auf n\u00fcchternen Magen oder nach dem Essen.<\/li>\n<li>W\u00e4hrend der Einnahme muss besonders streng auf Hygiene geachtet werden.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Es ist von entscheidender Bedeutung, die Art und Weise, wie Antibiotika verschrieben und angewendet werden, zu \u00e4ndern und Ma\u00dfnahmen zu ergreifen, um die Ausbreitung von Infektionen einzud\u00e4mmen<\/strong>, z. B. durch Impfungen und gute pers\u00f6nliche Hygiene (H\u00e4ndewaschen, Safer Sex zur Vermeidung von sexuell \u00fcbertragbaren Infektionen, Lebensmittelhygiene usw.).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Die gegenw\u00e4rtige Situation<\/strong><\/p>\n<p>T\u00e4glich treten neue Resistenzformen auf und verbreiten sich. <strong>Da die Wirksamkeit von Antibiotika nachl\u00e4sst, ist die Behandlung bei vielen Infektionen (Lungenentz\u00fcndung, Tuberkulose, Gonorrhoe, Syphilis, Blutvergiftung usw.) immer schwieriger.<\/strong> Das f\u00fchrt zu einer Erh\u00f6hung der Morbidit\u00e4t und Mortalit\u00e4t.<\/p>\n<p>Wenn sie nicht mit Antibiotika der ersten Wahl behandelt werden k\u00f6nnen, m\u00fcssen neuere Antibiotika eingesetzt werden.<\/p>\n<p>Die WHO \u00fcberwacht seit mehr als sieben Jahren mittels eines globalen strategischen Aktionsplans zur Bek\u00e4mpfung der Resistenz gegen antimikrobielle Mittel, einschlie\u00dflich der Antibiotikaresistenz, die Entwicklung genau. In diesem Sinne wurde auch die Kampagne \u201eWorld Antimicrobial Awareness Week\u201c ins Leben gerufen, die immer im November unter dem Motto \u201eVorsicht im Umgang mit Antibiotika\u201d stattfindet und Auswertung der ver\u00f6ffentlichten Studien und Themen beinhaltet.<\/p>\n<p>Dieses zunehmende Problem, das sowohl die Industrie- als auch die Entwicklungsl\u00e4nder betrifft, erfordert die Zusammenarbeit und Bewusstseinsbildung verschiedener Akteure: von der korrekten Verschreibung der Arzneimittel in den medizinischen Zentren \u00fcber die Pflicht der Patienten, sich nicht selbst zu behandeln und sie nur unter \u00e4rztlicher Aufsicht einzunehmen, bis hin zur Beteiligung der Regierungen an der Umsetzung von entsprechenden Initiativen und der F\u00f6rderung der Forschung. Es ist jedoch unser aller Aufgabe, die Ausbreitung der Resistenz gegen antimikrobielle Arzneimittel einzud\u00e4mmen.<\/p>\n<p style=\"text-align: right;\">Dr. Juan Antonio Andreo Ram\u00edrez<\/p>\n<p style=\"text-align: right;\">Medizinische Direktor f\u00fcr ASSSA<\/p>\n<h6><strong><u><a href=\"https:\/\/www.asssa.es\/de\/versicherung\/krankenversicherungen-\/\" target=\"_blank\" rel=\"noopener noreferrer\">Medizinische Leistungen ASSSA<\/a><\/u><\/strong><\/h6>\n<h6><em>Die ver\u00f6ffentlichte Information ersetzt in keinster Weise die direkte Konsultation mit einem Arzt, weder seine Diagnose noch den verschriebenen Behandlungsplan. Bitte auch nocht als Selbstdiagnoseverfahren verwenden.\u00a0<\/em><\/h6>\n<h6><em>Der Leser nutzt diesen Service in ausschliesslich eigener Verantwortung.\u00a0<\/em><\/h6>\n<h6><em>ASSSA empfiehlt, bei Fragen und Zweifeln sich zun\u00e4chst direkt an Ihren Arzt zu wenden.<\/em><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Antibiotika sind Medikamente, die zur Bek\u00e4mpfung bakterieller Infektionen eingesetzt werden. Wenn sie korrekt angewendet werden, k\u00f6nnen sie heilen und Leben retten. Wir begegnen jedoch Tag f\u00fcr Tag auch auf Probleme aufgrund resistenter Erreger. Jedes Mal, wenn wir ein Antibiotikum einnehmen, besteht die Gefahr, dass die Bakterien resistent werden, und diese Entwicklung ist progressiv und unaufhaltsam.<\/p>\n","protected":false},"author":17,"featured_media":14236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-14136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesundheit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Antibiotikaresistenz - ASSSA Deutsch<\/title>\n<meta name=\"description\" content=\"Antibiotika sind Medikamente, die zur Bek\u00e4mpfung bakterieller Infektionen eingesetzt werden. Wenn sie korrekt angewendet werden, k\u00f6nnen sie heilen und Leben retten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antibiotikaresistenz - ASSSA Deutsch\" \/>\n<meta property=\"og:description\" content=\"Antibiotika sind Medikamente, die zur Bek\u00e4mpfung bakterieller Infektionen eingesetzt werden. Wenn sie korrekt angewendet werden, k\u00f6nnen sie heilen und Leben retten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/\" \/>\n<meta property=\"og:site_name\" content=\"ASSSA Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-22T07:44:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/11\/imagen-blog_resistencia-antibioticos-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"297\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anabisquert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"anabisquert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/antibiotikaresistenz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/antibiotikaresistenz\\\/\"},\"author\":{\"name\":\"anabisquert\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\"},\"headline\":\"Antibiotikaresistenz\",\"datePublished\":\"2023-11-22T07:44:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/antibiotikaresistenz\\\/\"},\"wordCount\":630,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/antibiotikaresistenz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/imagen-blog_resistencia-antibioticos-2.jpg\",\"articleSection\":[\"Gesundheit\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/antibiotikaresistenz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/antibiotikaresistenz\\\/\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/antibiotikaresistenz\\\/\",\"name\":\"Antibiotikaresistenz - ASSSA Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/antibiotikaresistenz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/antibiotikaresistenz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/imagen-blog_resistencia-antibioticos-2.jpg\",\"datePublished\":\"2023-11-22T07:44:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\"},\"description\":\"Antibiotika sind Medikamente, die zur Bek\u00e4mpfung bakterieller Infektionen eingesetzt werden. Wenn sie korrekt angewendet werden, k\u00f6nnen sie heilen und Leben retten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/antibiotikaresistenz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/antibiotikaresistenz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/antibiotikaresistenz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/imagen-blog_resistencia-antibioticos-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/imagen-blog_resistencia-antibioticos-2.jpg\",\"width\":600,\"height\":297,\"caption\":\"Antibiotikaresistenz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/antibiotikaresistenz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antibiotikaresistenz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/\",\"name\":\"ASSSA Deutsch\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\",\"name\":\"anabisquert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"caption\":\"anabisquert\"},\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/author\\\/anabisquert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antibiotikaresistenz - ASSSA Deutsch","description":"Antibiotika sind Medikamente, die zur Bek\u00e4mpfung bakterieller Infektionen eingesetzt werden. Wenn sie korrekt angewendet werden, k\u00f6nnen sie heilen und Leben retten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/","og_locale":"de_DE","og_type":"article","og_title":"Antibiotikaresistenz - ASSSA Deutsch","og_description":"Antibiotika sind Medikamente, die zur Bek\u00e4mpfung bakterieller Infektionen eingesetzt werden. Wenn sie korrekt angewendet werden, k\u00f6nnen sie heilen und Leben retten.","og_url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/","og_site_name":"ASSSA Deutsch","article_published_time":"2023-11-22T07:44:33+00:00","og_image":[{"width":600,"height":297,"url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/11\/imagen-blog_resistencia-antibioticos-2.jpg","type":"image\/jpeg"}],"author":"anabisquert","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"anabisquert","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/#article","isPartOf":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/"},"author":{"name":"anabisquert","@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606"},"headline":"Antibiotikaresistenz","datePublished":"2023-11-22T07:44:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/"},"wordCount":630,"commentCount":0,"image":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/11\/imagen-blog_resistencia-antibioticos-2.jpg","articleSection":["Gesundheit"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/","url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/","name":"Antibiotikaresistenz - ASSSA Deutsch","isPartOf":{"@id":"https:\/\/www.asssa.es\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/#primaryimage"},"image":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/11\/imagen-blog_resistencia-antibioticos-2.jpg","datePublished":"2023-11-22T07:44:33+00:00","author":{"@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606"},"description":"Antibiotika sind Medikamente, die zur Bek\u00e4mpfung bakterieller Infektionen eingesetzt werden. Wenn sie korrekt angewendet werden, k\u00f6nnen sie heilen und Leben retten.","breadcrumb":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/#primaryimage","url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/11\/imagen-blog_resistencia-antibioticos-2.jpg","contentUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/11\/imagen-blog_resistencia-antibioticos-2.jpg","width":600,"height":297,"caption":"Antibiotikaresistenz"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/antibiotikaresistenz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asssa.es\/de\/"},{"@type":"ListItem","position":2,"name":"Antibiotikaresistenz"}]},{"@type":"WebSite","@id":"https:\/\/www.asssa.es\/de\/#website","url":"https:\/\/www.asssa.es\/de\/","name":"ASSSA Deutsch","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asssa.es\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606","name":"anabisquert","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","caption":"anabisquert"},"url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/author\/anabisquert\/"}]}},"jetpack_featured_media_url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2023\/11\/imagen-blog_resistencia-antibioticos-2.jpg","_links":{"self":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/14136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/comments?post=14136"}],"version-history":[{"count":1,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/14136\/revisions"}],"predecessor-version":[{"id":14137,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/14136\/revisions\/14137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/media\/14236"}],"wp:attachment":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/media?parent=14136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/categories?post=14136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/tags?post=14136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}