{"id":15073,"date":"2024-02-29T10:08:25","date_gmt":"2024-02-29T09:08:25","guid":{"rendered":"https:\/\/www.asssa.es\/de\/?p=15073"},"modified":"2024-02-29T10:08:25","modified_gmt":"2024-02-29T09:08:25","slug":"verbundenheit-in-der-krankenversicherung","status":"publish","type":"post","link":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/","title":{"rendered":"Verbundenheit in der Krankenversicherung"},"content":{"rendered":"<p>Menschen sind von Natur aus soziale Wesen. Wir haben das Bed\u00fcrfnis, uns begleitet zu f\u00fchlen, Bindungen einzugehen und Beziehungen zu anderen aufzubauen. All dies verleiht uns ein gr\u00f6\u00dferes Wohlbefinden, da wir wissen, dass andere an unserer Seite sein werden. Menschliche N\u00e4he ist daher in allen Bereichen unseres Lebens wichtig, aber besonders in Zeiten der Schw\u00e4che, wenn die Gesundheit beeintr\u00e4chtigt ist.<\/p>\n<p><!--more--><\/p>\n<p>Aus diesem Grund ist es wichtig, bei der Wahl einer Krankenversicherung darauf zu achten, dass die Mitarbeiter die Versicherten pers\u00f6nlich und mit menschlicher N\u00e4he betreuen, denn das macht einen gro\u00dfen Unterschied.<\/p>\n<p>Bei ASSSA <strong>achten wir auf Details in der Kommunikation <\/strong>und im <strong>Umgang mit den Versicherten und Interessenten<\/strong>, um h\u00f6chste Qualit\u00e4t zu bieten. Unser Kundenservice ist ein Team aus <strong>kompetenten, einf\u00fchlsamen und mehrsprachigen Personen<\/strong>, die sich mit Werten wie Berufung und Engagement identifizieren k\u00f6nnen.<\/p>\n<p><strong>Herzlichkeit sowie individuelle und professionelle Betreuung sind unsere Markenzeichen.<\/strong> Dazu verf\u00fcgen wir \u00fcber ein weit verzweigtes Netz von B\u00fcros an verschiedenen Standorten im ganzen Land und <strong>arbeiten auf eine pers\u00f6nliche Beziehung zu unseren Versicherten hin<\/strong>. Wir weisen ihnen von Anfang an einen Ansprechpartner zu, der ihnen bei allen Formalit\u00e4ten behilflich ist und in v\u00f6lliger Transparenz Probleme l\u00f6st. Dies gilt f\u00fcr den Vertragsabschluss als auch bei der Nutzung der verschiedenen Dienstleistungen.<\/p>\n<p>Dar\u00fcber hinaus verf\u00fcgen wir \u00fcber ein <strong>umfangreiches medizinisches \u00c4rzteverzeichnis, das sich vollkommen der Patientenversorgung widmet<\/strong> und aus exzellenten Fach\u00e4rzten besteht, die in Kliniken mit fortschrittlicher Technologie und internationalen Krankenh\u00e4usern eine unschlagbare und enge Gesundheitsversorgung gew\u00e4hrleisten. Mit dem Ziel, sich um die Menschen zu k\u00fcmmern, gehen sie auf deren Bed\u00fcrfnisse ein und bem\u00fchen sich um eine schnelle und genaue Diagnose und Behandlung. Um<strong> alle Menschen, auch anderer Nationalit\u00e4t, zu erreichen<\/strong>, verf\u00fcgen wir \u00fcber zahlreiche medizinische Zentren, die mehrsprachige Betreuung oder \u00dcbersetzungsdienste anbieten, damit die Kommunikation fl\u00fcssig und ohne Sprachbarrieren verl\u00e4uft.<\/p>\n<p><strong>Zu unserem einzigartigen und engen Service geh\u00f6rt auch die Digitalisierung.<\/strong> So sind wir bestrebt, unsere Zug\u00e4nglichkeit weiter zu verbessern, und stellen den Versicherten unsere Website in verschiedenen Sprachen zur Verf\u00fcgung. Dort k\u00f6nnen sie schnell und einfach das stets aktualisierte \u00c4rzteverzeichnis einsehen und auf das Kundenportal zugreifen, um detaillierte Informationen \u00fcber ihre Vertr\u00e4ge zu erhalten und Verfahren einfach und sicher durchzuf\u00fchren.<\/p>\n<p>All dies ist m\u00f6glich dank unserer <strong>\u00fcber 80-j\u00e4hrigen Erfahrung<\/strong> und unseres st\u00e4ndigen Bem\u00fchens, dass sich unsere Versicherten stets gesch\u00fctzt und gut begleitet f\u00fchlen.<\/p>\n<p><strong>Mit ASSSA f\u00fcr N\u00e4he und Professionalit\u00e4t in der Gesundheitsversorgung.<\/strong><\/p>\n<h6><strong><u><a href=\"https:\/\/www.asssa.es\/de\/versicherung\/krankenversicherungen-\/\" target=\"_blank\" rel=\"noopener noreferrer\">Medizinische Leistungen ASSSA<\/a><\/u><\/strong><\/h6>\n<h6><em>Die ver\u00f6ffentlichte Information ersetzt in keinster Weise die direkte Konsultation mit einem Arzt, weder seine Diagnose noch den verschriebenen Behandlungsplan. Bitte auch nocht als Selbstdiagnoseverfahren verwenden.\u00a0<\/em><\/h6>\n<h6><em>Der Leser nutzt diesen Service in ausschliesslich eigener Verantwortung.\u00a0<\/em><\/h6>\n<h6><em>ASSSA empfiehlt, bei Fragen und Zweifeln sich zun\u00e4chst direkt an Ihren Arzt zu wenden.<\/em><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Menschen sind von Natur aus soziale Wesen. Wir haben das Bed\u00fcrfnis, uns begleitet zu f\u00fchlen, Bindungen einzugehen und Beziehungen zu anderen aufzubauen. All dies verleiht uns ein gr\u00f6\u00dferes Wohlbefinden, da wir wissen, dass andere an unserer Seite sein werden. Menschliche N\u00e4he ist daher in allen Bereichen unseres Lebens wichtig, aber besonders in Zeiten der Schw\u00e4che, [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":15075,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-15073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-versicherungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verbundenheit in der Krankenversicherung - ASSSA Deutsch<\/title>\n<meta name=\"description\" content=\"Menschen sind von Natur aus soziale Wesen. Wir haben das Bed\u00fcrfnis, uns begleitet zu f\u00fchlen, Bindungen einzugehen und Beziehungen zu anderen aufzubauen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verbundenheit in der Krankenversicherung - ASSSA Deutsch\" \/>\n<meta property=\"og:description\" content=\"Menschen sind von Natur aus soziale Wesen. Wir haben das Bed\u00fcrfnis, uns begleitet zu f\u00fchlen, Bindungen einzugehen und Beziehungen zu anderen aufzubauen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/\" \/>\n<meta property=\"og:site_name\" content=\"ASSSA Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-29T09:08:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asssa.es\/wp-content\/uploads\/2024\/02\/imagen-blog-cercania-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"297\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"anabisquert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"anabisquert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/verbundenheit-in-der-krankenversicherung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/verbundenheit-in-der-krankenversicherung\\\/\"},\"author\":{\"name\":\"anabisquert\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\"},\"headline\":\"Verbundenheit in der Krankenversicherung\",\"datePublished\":\"2024-02-29T09:08:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/verbundenheit-in-der-krankenversicherung\\\/\"},\"wordCount\":490,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/verbundenheit-in-der-krankenversicherung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/imagen-blog-cercania-2.png\",\"articleSection\":[\"Versicherungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/verbundenheit-in-der-krankenversicherung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/verbundenheit-in-der-krankenversicherung\\\/\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/verbundenheit-in-der-krankenversicherung\\\/\",\"name\":\"Verbundenheit in der Krankenversicherung - ASSSA Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/verbundenheit-in-der-krankenversicherung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/verbundenheit-in-der-krankenversicherung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/imagen-blog-cercania-2.png\",\"datePublished\":\"2024-02-29T09:08:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\"},\"description\":\"Menschen sind von Natur aus soziale Wesen. Wir haben das Bed\u00fcrfnis, uns begleitet zu f\u00fchlen, Bindungen einzugehen und Beziehungen zu anderen aufzubauen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/verbundenheit-in-der-krankenversicherung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/verbundenheit-in-der-krankenversicherung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/verbundenheit-in-der-krankenversicherung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/imagen-blog-cercania-2.png\",\"contentUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/imagen-blog-cercania-2.png\",\"width\":600,\"height\":297,\"caption\":\"Verbundenheit in der Krankenversicherung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/verbundenheit-in-der-krankenversicherung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verbundenheit in der Krankenversicherung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/\",\"name\":\"ASSSA Deutsch\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\",\"name\":\"anabisquert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"caption\":\"anabisquert\"},\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/author\\\/anabisquert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verbundenheit in der Krankenversicherung - ASSSA Deutsch","description":"Menschen sind von Natur aus soziale Wesen. Wir haben das Bed\u00fcrfnis, uns begleitet zu f\u00fchlen, Bindungen einzugehen und Beziehungen zu anderen aufzubauen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/","og_locale":"de_DE","og_type":"article","og_title":"Verbundenheit in der Krankenversicherung - ASSSA Deutsch","og_description":"Menschen sind von Natur aus soziale Wesen. Wir haben das Bed\u00fcrfnis, uns begleitet zu f\u00fchlen, Bindungen einzugehen und Beziehungen zu anderen aufzubauen.","og_url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/","og_site_name":"ASSSA Deutsch","article_published_time":"2024-02-29T09:08:25+00:00","og_image":[{"width":600,"height":297,"url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2024\/02\/imagen-blog-cercania-2.png","type":"image\/png"}],"author":"anabisquert","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"anabisquert","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/#article","isPartOf":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/"},"author":{"name":"anabisquert","@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606"},"headline":"Verbundenheit in der Krankenversicherung","datePublished":"2024-02-29T09:08:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/"},"wordCount":490,"commentCount":0,"image":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2024\/02\/imagen-blog-cercania-2.png","articleSection":["Versicherungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/","url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/","name":"Verbundenheit in der Krankenversicherung - ASSSA Deutsch","isPartOf":{"@id":"https:\/\/www.asssa.es\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/#primaryimage"},"image":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2024\/02\/imagen-blog-cercania-2.png","datePublished":"2024-02-29T09:08:25+00:00","author":{"@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606"},"description":"Menschen sind von Natur aus soziale Wesen. Wir haben das Bed\u00fcrfnis, uns begleitet zu f\u00fchlen, Bindungen einzugehen und Beziehungen zu anderen aufzubauen.","breadcrumb":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/#primaryimage","url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2024\/02\/imagen-blog-cercania-2.png","contentUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2024\/02\/imagen-blog-cercania-2.png","width":600,"height":297,"caption":"Verbundenheit in der Krankenversicherung"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/verbundenheit-in-der-krankenversicherung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asssa.es\/de\/"},{"@type":"ListItem","position":2,"name":"Verbundenheit in der Krankenversicherung"}]},{"@type":"WebSite","@id":"https:\/\/www.asssa.es\/de\/#website","url":"https:\/\/www.asssa.es\/de\/","name":"ASSSA Deutsch","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asssa.es\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606","name":"anabisquert","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","caption":"anabisquert"},"url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/author\/anabisquert\/"}]}},"jetpack_featured_media_url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2024\/02\/imagen-blog-cercania-2.png","_links":{"self":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/15073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/comments?post=15073"}],"version-history":[{"count":1,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/15073\/revisions"}],"predecessor-version":[{"id":15074,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/15073\/revisions\/15074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/media\/15075"}],"wp:attachment":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/media?parent=15073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/categories?post=15073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/tags?post=15073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}