{"id":20092,"date":"2025-04-16T12:35:23","date_gmt":"2025-04-16T10:35:23","guid":{"rendered":"https:\/\/www.asssa.es\/de\/?p=20092"},"modified":"2025-04-16T12:35:23","modified_gmt":"2025-04-16T10:35:23","slug":"stimmpflege","status":"publish","type":"post","link":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/","title":{"rendered":"Stimmpflege"},"content":{"rendered":"<p>Die Stimme ist jener Klang, den wir erzeugen, wenn wir sprechen, singen oder eine andere Art der stimmlichen Kommunikation praktizieren. Sie wird im Kehlkopf erzeugt, und zwar durch die willentliche Bewegung der Stimmb\u00e4nder beim Ausstr\u00f6men der Luft aus der Lunge.<\/p>\n<p><!--more--><\/p>\n<p>Sie ist ein \u00e4u\u00dferst wertvolles Werkzeug; ihre enorme Bedeutung liegt darin, dass sie uns f\u00fcr die Kommunikation untereinander, ja, sogar f\u00fcrs \u00dcberleben \u00fcberaus n\u00fctzlich ist.<\/p>\n<p>Es wird gesch\u00e4tzt, dass etwa 5 % der Bev\u00f6lkerung an einer Stimmst\u00f6rung leiden, die eine Behandlung durch einen Spezialisten erfordert.<\/p>\n<p><strong>Die Stimme ver\u00e4ndert sich, wenn verschiedene Erkrankungen der Stimmb\u00e4nder auftreten oder neurologische und\/oder psychiatrische Gr\u00fcnde vorliegen.<\/strong> Diese Erkrankungen werden von Hals-Nasen-Ohren\u00e4rzten (HNO) mittels fibroskopischer Kehlkopfuntersuchung und\/oder Stroboskopie diagnostiziert und behandelt \u2013 Methoden, die eine pr\u00e4zise Visualisierung der Stimmb\u00e4nder sowie die Beurteilung ihrer Beweglichkeit und Vibration w\u00e4hrend der Phonation erm\u00f6glichen. Mit diesen Verfahren k\u00f6nnen folgende Erkrankungen diagnostiziert werden:<\/p>\n<ul>\n<li>Knoten: Diese verbessern sich vor allem durch Rehabilitation.<\/li>\n<li>Polypen: Sie werden h\u00e4ufig mit chirurgischen Methoden behandelt.<\/li>\n<li>Laryngitis: Akute oder chronische Entz\u00fcndungen des Kehlkopfes, verursacht durch Infektionsprozesse und h\u00e4ufig auch durch gastro\u00f6sophagealen Reflux.<\/li>\n<li>Stimmbandl\u00e4hmungen: Diese entstehen oft nach fr\u00fcheren Operationen an der Schilddr\u00fcse, am Herzen oder sie haben idiopathische (verschiedene m\u00f6gliche) Ursachen, etc.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Bei neurologischen oder psychiatrischen Problemen sind die Stimmb\u00e4nder an sich normal, jedoch ist ihre Funktionalit\u00e4t beeintr\u00e4chtigt.<\/p>\n<p>Ebenso sind Personen, die aufgrund beruflicher oder anderer Gr\u00fcnde viel ihre Stimme verwenden, st\u00e4rker gef\u00e4hrdet, Probleme zu entwickeln, die durch eine falsche Anwendung oder \u00dcberbeanspruchung der Stimme entstehen.<\/p>\n<p>All diese Probleme k\u00f6nnen, wenn keine andere L\u00f6sung m\u00f6glich ist, durch Logop\u00e4die, durch Medikamente im Fall von gastro\u00f6sophagealem Reflux oder bei infekti\u00f6ser Laryngitis oder durch eine Operation bei Polypen und L\u00e4hmungen behandelt werden. <strong>Es ist \u00e4u\u00dferst wichtig, dass jeder Einzelne aktiv dazu beitr\u00e4gt, seine Stimme zu st\u00e4rken und eine weitere Verschlechterung zu vermeiden.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>Wie k\u00f6nnen wir unsere Stimme pflegen?<\/strong><\/p>\n<p><strong>Fl\u00fcssigkeitszufuhr:<\/strong> Man sollte ausreichend Wasser zu trinken \u2013 mindestens 1,5 Liter pro Tag \u2013, um die Stimmb\u00e4nder gut mit Feuchtigkeit zu versorgen.<\/p>\n<p><strong>Reizstoffe vermeiden<\/strong>: Der Konsum von Alkohol, Koffein und Tabak sollte reduziert oder vermieden werden, da diese die Stimme austrocknen und die Funktion der Stimmb\u00e4nder beeintr\u00e4chtigen k\u00f6nnen.<\/p>\n<p><strong>Aufw\u00e4rm\u00fcbungen f\u00fcr die Stimme:<\/strong> Vor l\u00e4ngeren Sprechphasen, langen Gespr\u00e4chen oder Gesang sind Aufw\u00e4rm\u00fcbungen f\u00fcr die Stimme ratsam, um die Stimmb\u00e4nder auf die Belastung vorzubereiten.<\/p>\n<p><strong>Ruhephasen<\/strong>: Es ist wichtig, der Stimme auch mal Ruhe zu g\u00f6nnen, insbesondere nach intensiver Nutzung.<\/p>\n<p><strong>Haltung<\/strong>: Es sollte eine gute Haltung beim Sprechen oder Singen eingenommen werden, um die Atmung und die Stimmwiedergabe zu erleichtern.<\/p>\n<p><strong>Ern\u00e4hrung<\/strong>: Eine Antireflux-Ern\u00e4hrung ist ratsam, besonders in F\u00e4llen von Hiatushernie, Gastritis oder \u00e4hnlichen Beschwerden.<\/p>\n<p>Zusammenfassend l\u00e4sst sich sagen, dass man seine Stimme pflegen, auf eine gesunde Ern\u00e4hrung achten und sich regelm\u00e4\u00dfig k\u00f6rperlich bet\u00e4tigen sollte, um einen klaren Geist zu bewahren. All dies tr\u00e4gt dazu bei, Probleme mit den Stimmb\u00e4ndern weitgehend zu vermeiden und gleichzeitig die k\u00f6rperliche sowie die geistige Gesundheit zu f\u00f6rdern.<\/p>\n<p style=\"text-align: right;\">Dr. Laura Ga\u00f1an<\/p>\n<p style=\"text-align: right;\">Hals-Nasen-Ohren-\u00c4rztin (HNO)<\/p>\n<p style=\"text-align: right;\">Medizinisches Zentrum La Rueda<\/p>\n<p>&nbsp;<\/p>\n<h6><strong><u><a href=\"https:\/\/www.asssa.es\/de\/versicherung\/krankenversicherungen-\/\" target=\"_blank\" rel=\"noopener noreferrer\">Medizinische Leistungen ASSSA<\/a><\/u><\/strong><\/h6>\n<h6><em>Die ver\u00f6ffentlichte Information ersetzt in keinster Weise die direkte Konsultation mit einem Arzt, weder seine Diagnose noch den verschriebenen Behandlungsplan. Bitte auch nocht als Selbstdiagnoseverfahren verwenden.\u00a0<\/em><\/h6>\n<h6><em>Der Leser nutzt diesen Service in ausschliesslich eigener Verantwortung.\u00a0<\/em><\/h6>\n<h6><em>ASSSA empfiehlt, bei Fragen und Zweifeln sich zun\u00e4chst direkt an Ihren Arzt zu wenden.<\/em><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Die Stimme ist jener Klang, den wir erzeugen, wenn wir sprechen, singen oder eine andere Art der stimmlichen Kommunikation praktizieren. Sie wird im Kehlkopf erzeugt, und zwar durch die willentliche Bewegung der Stimmb\u00e4nder beim Ausstr\u00f6men der Luft aus der Lunge.<\/p>\n","protected":false},"author":17,"featured_media":20093,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-20092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesundheit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stimmpflege - ASSSA Deutsch<\/title>\n<meta name=\"description\" content=\"Die Stimme ist jener Klang, den wir erzeugen, wenn wir sprechen, singen oder eine andere Art der stimmlichen Kommunikation praktizieren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stimmpflege - ASSSA Deutsch\" \/>\n<meta property=\"og:description\" content=\"Die Stimme ist jener Klang, den wir erzeugen, wenn wir sprechen, singen oder eine andere Art der stimmlichen Kommunikation praktizieren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/\" \/>\n<meta property=\"og:site_name\" content=\"ASSSA Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-16T10:35:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asssa.es\/wp-content\/uploads\/2025\/04\/imagen-blog-voz-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"297\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"anabisquert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"anabisquert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/stimmpflege\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/stimmpflege\\\/\"},\"author\":{\"name\":\"anabisquert\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\"},\"headline\":\"Stimmpflege\",\"datePublished\":\"2025-04-16T10:35:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/stimmpflege\\\/\"},\"wordCount\":601,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/stimmpflege\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/imagen-blog-voz-2.png\",\"articleSection\":[\"Gesundheit\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/stimmpflege\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/stimmpflege\\\/\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/stimmpflege\\\/\",\"name\":\"Stimmpflege - ASSSA Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/stimmpflege\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/stimmpflege\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/imagen-blog-voz-2.png\",\"datePublished\":\"2025-04-16T10:35:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\"},\"description\":\"Die Stimme ist jener Klang, den wir erzeugen, wenn wir sprechen, singen oder eine andere Art der stimmlichen Kommunikation praktizieren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/stimmpflege\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/stimmpflege\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/stimmpflege\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/imagen-blog-voz-2.png\",\"contentUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/imagen-blog-voz-2.png\",\"width\":600,\"height\":297},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/stimmpflege\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stimmpflege\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/\",\"name\":\"ASSSA Deutsch\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\",\"name\":\"anabisquert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"caption\":\"anabisquert\"},\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/author\\\/anabisquert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stimmpflege - ASSSA Deutsch","description":"Die Stimme ist jener Klang, den wir erzeugen, wenn wir sprechen, singen oder eine andere Art der stimmlichen Kommunikation praktizieren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/","og_locale":"de_DE","og_type":"article","og_title":"Stimmpflege - ASSSA Deutsch","og_description":"Die Stimme ist jener Klang, den wir erzeugen, wenn wir sprechen, singen oder eine andere Art der stimmlichen Kommunikation praktizieren.","og_url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/","og_site_name":"ASSSA Deutsch","article_published_time":"2025-04-16T10:35:23+00:00","og_image":[{"width":600,"height":297,"url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2025\/04\/imagen-blog-voz-2.png","type":"image\/png"}],"author":"anabisquert","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"anabisquert","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/#article","isPartOf":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/"},"author":{"name":"anabisquert","@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606"},"headline":"Stimmpflege","datePublished":"2025-04-16T10:35:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/"},"wordCount":601,"commentCount":0,"image":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2025\/04\/imagen-blog-voz-2.png","articleSection":["Gesundheit"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/","url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/","name":"Stimmpflege - ASSSA Deutsch","isPartOf":{"@id":"https:\/\/www.asssa.es\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/#primaryimage"},"image":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2025\/04\/imagen-blog-voz-2.png","datePublished":"2025-04-16T10:35:23+00:00","author":{"@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606"},"description":"Die Stimme ist jener Klang, den wir erzeugen, wenn wir sprechen, singen oder eine andere Art der stimmlichen Kommunikation praktizieren.","breadcrumb":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/#primaryimage","url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2025\/04\/imagen-blog-voz-2.png","contentUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2025\/04\/imagen-blog-voz-2.png","width":600,"height":297},{"@type":"BreadcrumbList","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/stimmpflege\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asssa.es\/de\/"},{"@type":"ListItem","position":2,"name":"Stimmpflege"}]},{"@type":"WebSite","@id":"https:\/\/www.asssa.es\/de\/#website","url":"https:\/\/www.asssa.es\/de\/","name":"ASSSA Deutsch","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asssa.es\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606","name":"anabisquert","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","caption":"anabisquert"},"url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/author\/anabisquert\/"}]}},"jetpack_featured_media_url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2025\/04\/imagen-blog-voz-2.png","_links":{"self":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/20092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/comments?post=20092"}],"version-history":[{"count":1,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/20092\/revisions"}],"predecessor-version":[{"id":20094,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/20092\/revisions\/20094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/media\/20093"}],"wp:attachment":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/media?parent=20092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/categories?post=20092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/tags?post=20092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}