{"id":23701,"date":"2026-01-29T08:31:38","date_gmt":"2026-01-29T07:31:38","guid":{"rendered":"https:\/\/www.asssa.es\/de\/?p=23701"},"modified":"2026-01-29T08:31:38","modified_gmt":"2026-01-29T07:31:38","slug":"der-arzt-eine-schluesselrolle-in-der-krankenversicherung","status":"publish","type":"post","link":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/","title":{"rendered":"Der Arzt: eine Schl\u00fcsselrolle in der Krankenversicherung"},"content":{"rendered":"<p>Medizinische Fachkr\u00e4fte sind Schl\u00fcsselfiguren in der Gesellschaft und daher auch in der Krankenversicherung. Sie behandeln nicht nur Krankheiten, sondern begleiten, beugen vor, h\u00f6ren zu und unterst\u00fctzen die Menschen. Sie sind daher wichtig, um die Lebensqualit\u00e4t zu verbessern und das Wohlbefinden zu f\u00f6rdern.<\/p>\n<p><!--more--><\/p>\n<p>In einer Praxis verwenden sie neben Apparatur wie dem Stethoskop auch Instrumente wie Empathie, menschliche Zuwendung und effektive Kommunikation. Dar\u00fcber hinaus arbeiten sie auch mit anderen Fachleuten zusammen, um verschiedene gesundheitliche Herausforderungen anzugehen und effiziente Diagnosen und Ergebnisse zu erzielen.<\/p>\n<p>Aus all diesen Gr\u00fcnden ist es von grundlegender Bedeutung, dass der Arzt qualifiziert, ausgebildet und erfahren ist. So kann er seine Patienten richtig versorgen und ihnen in allen Lebensphasen professionell und einf\u00fchlsam die notwendige Betreuung zukommen lassen.<\/p>\n<p>Bei ASSSA sind wir uns der Bedeutung einer exzellenten medizinischen Versorgung durch \u00c4rzte, die sich aufrichtig f\u00fcr die Gesundheit der Versicherten interessieren, voll und ganz bewusst.<\/p>\n<p>Im Rahmen unseres Kompromisses einer umfassenden und erstklassigen Betreuung, verf\u00fcgen wir \u00fcber ein umfangreiches \u00c4rzteverzeichnis mit vertrauensw\u00fcrdigen Fach\u00e4rzten und Zentren, mit denen wir <strong>in direktem und st\u00e4ndigem Kontakt stehen<\/strong>. Ebenso <strong>h\u00f6ren wir unseren Versicherten zu<\/strong>, um ihre Zufriedenheit zu erfahren, und ber\u00fccksichtigen ihre W\u00fcnsche und Vorschl\u00e4ge, um ihren Erwartungen gerecht zu werden.<\/p>\n<p>Um eine <strong>gr\u00f6\u00dfere Auswahl an Optionen<\/strong> in verschiedenen Regionen anzubieten, arbeiten wir daran, unsere Pr\u00e4senz zu st\u00e4rken, indem wir Fachgebiete in unser \u00c4rzteverzeichnis aufnehmen, die den lokalen Bed\u00fcrfnissen entsprechen. Um Sprachbarrieren zu beseitigen, haben wir <strong>zahlreiche mehrsprachige Zentren oder Einrichtungen mit \u00dcbersetzungsdienst<\/strong> sowie international renommierte Krankenh\u00e4user in unser Verzeichnis aufgenommen.<\/p>\n<p>Wir wissen, wie wichtig Seelenfrieden ist. Deshalb bieten wir <strong>direkten Zugang zu einer Vielzahl von Fach\u00e4rzten<\/strong> und die M\u00f6glichkeit einer <strong>zweiten medizinischen Meinung<\/strong>, was mehr Sicherheit bei der Diagnose und Behandlung bietet.<\/p>\n<p>Dar\u00fcber hinaus stellen wir unseren Versicherten verschiedene Anwendungen zur Verf\u00fcgung, wie z. B. das jederzeit aktualisierte <strong>\u00c4rzteverzeichnis auf der Website<\/strong>, das <strong>Kundenportal<\/strong> f\u00fcr Online-Verwaltungsvorg\u00e4nge und die <strong>elektronische und virtuelle Karte<\/strong> f\u00fcr einen bequemen und einfachen Zugang zu den Dienstleistungen.<\/p>\n<p>Bei ASSSA k\u00fcmmern wir uns um jedes Detail, um eine Gesundheitsversorgung von h\u00f6chster Qualit\u00e4t zu gew\u00e4hrleisten und unser Ziel, den Schutz der Gesundheit, zu erf\u00fcllen.<\/p>\n<h6><strong><u><a href=\"https:\/\/www.asssa.es\/de\/versicherung\/krankenversicherungen-\/\" target=\"_blank\" rel=\"noopener noreferrer\">Medizinische Leistungen ASSSA<\/a><\/u><\/strong><\/h6>\n<h6><em>Die ver\u00f6ffentlichte Information ersetzt in keinster Weise die direkte Konsultation mit einem Arzt, weder seine Diagnose noch den verschriebenen Behandlungsplan. Bitte auch nocht als Selbstdiagnoseverfahren verwenden.\u00a0<\/em><\/h6>\n<h6><em>Der Leser nutzt diesen Service in ausschliesslich eigener Verantwortung.\u00a0<\/em><\/h6>\n<h6><em>ASSSA empfiehlt, bei Fragen und Zweifeln sich zun\u00e4chst direkt an Ihren Arzt zu wenden.<\/em><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Medizinische Fachkr\u00e4fte sind Schl\u00fcsselfiguren in der Gesellschaft und daher auch in der Krankenversicherung. Sie behandeln nicht nur Krankheiten, sondern begleiten, beugen vor, h\u00f6ren zu und unterst\u00fctzen die Menschen. Sie sind daher wichtig, um die Lebensqualit\u00e4t zu verbessern und das Wohlbefinden zu f\u00f6rdern.<\/p>\n","protected":false},"author":17,"featured_media":23703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-23701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-versicherungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der Arzt: eine Schl\u00fcsselrolle in der Krankenversicherung - ASSSA Deutsch<\/title>\n<meta name=\"description\" content=\"Medizinische Fachkr\u00e4fte sind Schl\u00fcsselfiguren in der Gesellschaft und daher auch in der Krankenversicherung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Arzt: eine Schl\u00fcsselrolle in der Krankenversicherung - ASSSA Deutsch\" \/>\n<meta property=\"og:description\" content=\"Medizinische Fachkr\u00e4fte sind Schl\u00fcsselfiguren in der Gesellschaft und daher auch in der Krankenversicherung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/\" \/>\n<meta property=\"og:site_name\" content=\"ASSSA Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-29T07:31:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asssa.es\/wp-content\/uploads\/2026\/01\/imagen-blog-Seguros-37-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"297\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"anabisquert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"anabisquert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\\\/\"},\"author\":{\"name\":\"anabisquert\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\"},\"headline\":\"Der Arzt: eine Schl\u00fcsselrolle in der Krankenversicherung\",\"datePublished\":\"2026-01-29T07:31:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\\\/\"},\"wordCount\":440,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/imagen-blog-Seguros-37-1.png\",\"articleSection\":[\"Versicherungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\\\/\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\\\/\",\"name\":\"Der Arzt: eine Schl\u00fcsselrolle in der Krankenversicherung - ASSSA Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/imagen-blog-Seguros-37-1.png\",\"datePublished\":\"2026-01-29T07:31:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\"},\"description\":\"Medizinische Fachkr\u00e4fte sind Schl\u00fcsselfiguren in der Gesellschaft und daher auch in der Krankenversicherung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/imagen-blog-Seguros-37-1.png\",\"contentUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/imagen-blog-Seguros-37-1.png\",\"width\":600,\"height\":297},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Arzt: eine Schl\u00fcsselrolle in der Krankenversicherung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/\",\"name\":\"ASSSA Deutsch\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/28426677ce1ecdf429f899be3593c606\",\"name\":\"anabisquert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g\",\"caption\":\"anabisquert\"},\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/author\\\/anabisquert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Arzt: eine Schl\u00fcsselrolle in der Krankenversicherung - ASSSA Deutsch","description":"Medizinische Fachkr\u00e4fte sind Schl\u00fcsselfiguren in der Gesellschaft und daher auch in der Krankenversicherung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/","og_locale":"de_DE","og_type":"article","og_title":"Der Arzt: eine Schl\u00fcsselrolle in der Krankenversicherung - ASSSA Deutsch","og_description":"Medizinische Fachkr\u00e4fte sind Schl\u00fcsselfiguren in der Gesellschaft und daher auch in der Krankenversicherung.","og_url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/","og_site_name":"ASSSA Deutsch","article_published_time":"2026-01-29T07:31:38+00:00","og_image":[{"width":600,"height":297,"url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2026\/01\/imagen-blog-Seguros-37-1.png","type":"image\/png"}],"author":"anabisquert","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"anabisquert","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/#article","isPartOf":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/"},"author":{"name":"anabisquert","@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606"},"headline":"Der Arzt: eine Schl\u00fcsselrolle in der Krankenversicherung","datePublished":"2026-01-29T07:31:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/"},"wordCount":440,"commentCount":0,"image":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2026\/01\/imagen-blog-Seguros-37-1.png","articleSection":["Versicherungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/","url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/","name":"Der Arzt: eine Schl\u00fcsselrolle in der Krankenversicherung - ASSSA Deutsch","isPartOf":{"@id":"https:\/\/www.asssa.es\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/#primaryimage"},"image":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2026\/01\/imagen-blog-Seguros-37-1.png","datePublished":"2026-01-29T07:31:38+00:00","author":{"@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606"},"description":"Medizinische Fachkr\u00e4fte sind Schl\u00fcsselfiguren in der Gesellschaft und daher auch in der Krankenversicherung.","breadcrumb":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/#primaryimage","url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2026\/01\/imagen-blog-Seguros-37-1.png","contentUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2026\/01\/imagen-blog-Seguros-37-1.png","width":600,"height":297},{"@type":"BreadcrumbList","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/der-arzt-eine-schluesselrolle-in-der-krankenversicherung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asssa.es\/de\/"},{"@type":"ListItem","position":2,"name":"Der Arzt: eine Schl\u00fcsselrolle in der Krankenversicherung"}]},{"@type":"WebSite","@id":"https:\/\/www.asssa.es\/de\/#website","url":"https:\/\/www.asssa.es\/de\/","name":"ASSSA Deutsch","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asssa.es\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/28426677ce1ecdf429f899be3593c606","name":"anabisquert","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e9cae4df96875fce5fb542f19394d31947278addfbdcdc1f4b3381f226af94d5?s=96&d=mm&r=g","caption":"anabisquert"},"url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/author\/anabisquert\/"}]}},"jetpack_featured_media_url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2026\/01\/imagen-blog-Seguros-37-1.png","_links":{"self":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/23701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/comments?post=23701"}],"version-history":[{"count":1,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/23701\/revisions"}],"predecessor-version":[{"id":23702,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/23701\/revisions\/23702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/media\/23703"}],"wp:attachment":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/media?parent=23701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/categories?post=23701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/tags?post=23701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}