{"id":4707,"date":"2018-10-17T09:00:00","date_gmt":"2018-10-17T07:00:00","guid":{"rendered":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/"},"modified":"2019-10-18T14:46:16","modified_gmt":"2019-10-18T12:46:16","slug":"was-genau-ist-helicobacter-pylori","status":"publish","type":"post","link":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/","title":{"rendered":"Was genau ist Helicobacter pylori?"},"content":{"rendered":"<p>Der menschliche Magen stellt ein sehr feindliches Milieu f&uuml;r jeden Mikroorganismus dar. Um die Verdauung der Nahrungsmittel vorzunehmen, sondert er gro&szlig;e Mengen Salzs&auml;ure ab, sodass der pH-Wert in der Regel unter 2 liegt.<\/p>\n<p>&nbsp;<\/p>\n<p>Dennoch gibt es ein Bakterium, das es schafft, in einem so aggressiven Milieu zu leben. Es hei&szlig;t Helicobacter pylori. Sie haben sicherlich schon davon geh&ouml;rt. Es ist ein spiroidf&ouml;rmiger Bazillus und ein Flagellum oder Gei&szlig;el, die es ihm erlauben, sich schnell durch den Schleim zu bewegen, der die Magenwand &uuml;berzieht. Es erzeugt eine gro&szlig;e Menge eines Enzyms namens Urease, das in der Lage ist, seine Umgebung zu alkalisieren und dadurch ein nicht saures &ldquo;Mikroklima&rdquo; zu schaffen. Es wurde 1982 von den Forschern Warren und Marshall entdeckt. Sie behaupteten, dass diese Infektion die Ursache von Duodenal- und Magengeschw&uuml;ren war, und nicht Stress und Lebensstil, wie damals angenommen wurde. Sie wurden von ihren Kollegen heftig kritisiert, aber die Zeit gab ihnen Recht und sie wurden schlie&szlig;lich f&uuml;r ihre Entdeckung im Jahr 2005 mit dem Nobelpreis ausgezeichnet.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Infektion wird von Mensch zu Mensch durch den Stuhl &uuml;bertragen und der Anteil der Infizierten w&auml;chst mit dem Alter. Viel h&auml;ufiger kommt die Infektion in Entwicklungsl&auml;nder vor, deren erwachsene Bev&ouml;lkerung eine Infektionsrate von 80% aufweist. In Industriel&auml;ndern wie den unseren liegt die Infektionsrate bei ca. 10% bei Erwachsenen im Alter von 18 bis 30 Jahren und bei 50% bei Personen ab 60 Jahren. Die Magenbesiedelung allein reicht nicht aus, um die Krankheit zu verursachen. Es gibt andere Faktoren, die vom Wirt und der Umgebung abh&auml;ngen, sodass nur 15-20% der infizierten Menschen H. pylori-bedingte Symptome entwickeln. Die H. pylori-Infektion verursacht eine Art von Gastritis, die als chronische aktive Gastritis bezeichnet wird. Diese Gastritis verursacht an sich keine Symptome, zumindest bei den meisten Patienten. Was jedoch Symptome verursacht sind die mit H. pylori assoziierten Krankheiten, wie das Zw&ouml;lffingerdarmgeschw&uuml;r (Ulcus duodeni), das Magengeschw&uuml;r, das Magen-Lymphom Typ MALT und das Adenokarzinom des Magens. Die Diagnose einer dieser Krankheiten ist ein klares Indiz daf&uuml;r, die Infektion zu beseitigen und dadurch einen R&uuml;ckfall der Krankheit zu verhindern. Weitere Situationen, in denen die H. pylori-Forschung und Eradikation in Betracht gezogen werden k&ouml;nnen, sind die Koexistenz anderer Bedingungen, die ebenfalls ein erh&ouml;htes Risiko f&uuml;r H. pylori-bedingte Krankheiten darstellen. Ein Beispiel w&auml;re die Notwendigkeit einer Langzeitbehandlung mit Aspirin oder nichtsteroidalen entz&uuml;ndungshemmenden Medikamenten, da diese Medikamente Magen- oder Zw&ouml;lffingerdarmgeschw&uuml;re verursachen k&ouml;nnen.<\/p>\n<p>&nbsp;<\/p>\n<p>Eine andere Situation kann auch das erh&ouml;hte Risiko von Magenkrebs bei Menschen mit einer hohen genetischen Belastung dieser Krankheit sein, was durch die Existenz einer Familiengeschichte belegt wird. Besonders hervorzuheben ist die funktionelle Dyspepsie. Patienten mit dieser Erkrankung haben chronische oder intermittierende Symptome, die denen von Magengeschw&uuml;ren oder Magenkrebs &auml;hneln, wie Epigastralgie (Schmerzen in der Magenm&uuml;ndung), Bl&auml;hungen nach den Mahlzeiten, eine schwere oder langsame Verdauung oder fr&uuml;hzeitiges S&auml;ttigungsgef&uuml;hl (S&auml;ttigung nach geringf&uuml;gigem Essen). Der Schl&uuml;ssel zur Diagnose ist die Existenz dieser Symptome und das Fehlen von L&auml;sionen im Magen und Zw&ouml;lffingerdarm, was durch eine Gastroskopie belegt wird.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Erkrankung ist chronisch und reagiert kaum auf die Behandlung. Die Infektionsrate durch H. pylori bei Patienten mit funktioneller Dyspepsie ist die gleiche wie bei der allgemeinen Bev&ouml;lkerung, und in den meisten F&auml;llen ist die Infektion nicht mit Symptomen verbunden. Bei etwa 10% der Patienten mit funktioneller Dyspepsie und H. pylori-Infektion kann es jedoch zu einer anhaltenden Besserung der Symptome kommen, wenn die Infektion beseitigt wird. Daher sollte zumindest in F&auml;llen, in denen die Symptome schwerwiegend und anhaltend sind, eine Eradikationstherapie in Betracht gezogen werden. Die Diagnose kann leicht mit einem Atemtest oder einer Stuhlanalyse durchgef&uuml;hrt werden, aber auch w&auml;hrend der Gastroskopie durch Entnahme von Proben aus der Magenschleimhaut. In allen F&auml;llen sollte der Patient 2 Wochen vor der Durchf&uuml;hrung der Studie auf die Einnahme von Protonenpumpen-Inhibitoren (Omeprazol o.&auml;.) und 1 Monat vor der Studie auf jegliche Art von Antibiotika verzichten. Eradikationstherapien basieren auf einer Kombination von starken Anti-Sekretions-Medikamenten und mindestens 2 Antibiotika, die alle f&uuml;r 10 bis 14 Tage eingenommen werden. Nat&uuml;rlich sollte nach der Eradikationstherapie gepr&uuml;ft werden, ob die Infektion beseitigt wurde. Hierf&uuml;r sind Atemtests oder die Bestimmung des H. pylori-Antigens im Stuhl besonders geeignet, da es sich um Methoden handelt, die keine Endoskopie erfordern. Mit den aktuellen Richtlinien wird die Eradikation in der Regel bei mehr als 90% der Patienten erreicht, die in der Lage sind, den Behandlungszyklus abzuschlie&szlig;en. Nach einer Heilung kommt es selten vor, dass sich die Infektion wiederholt. Die Wiederinfektionsrate nach erfolgreicher Eradikation liegt bei etwa 1% pro Jahr.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><u><strong><a href=\"https:\/\/www.asssa.es\/de\/versicherung\/krankenversicherungen-\/\" target=\"_blank\" rel=\"noopener noreferrer\">Medizinische Leistungen ASSSA<\/a><\/strong><\/u><\/p>\n<p>&nbsp;<\/p>\n<p><em>Die ver&ouml;ffentlichte Information ersetzt in keinster Weise die direkte Konsultation mit einem Arzt, weder seine Diagnose noch den verschriebenen Behandlungsplan. Bitte auch nocht als Selbstdiagnoseverfahren verwenden.&nbsp;<\/em><\/p>\n<p><em>Der Leser nutzt diesen Service in ausschliesslich eigener Verantwortung.&nbsp;<\/em><\/p>\n<p><em>ASSSA empfiehlt, bei Fragen und Zweifeln sich zun&auml;chst direkt an Ihren Arzt zu wenden.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der menschliche Magen stellt ein sehr feindliches Milieu f&uuml;r jeden Mikroorganismus dar. Um die Verdauung der Nahrungsmittel vorzunehmen, sondert er gro&szlig;e Mengen Salzs&auml;ure ab, sodass der pH-Wert in der Regel unter 2 liegt.<\/p>\n","protected":false},"author":20,"featured_media":4708,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-4707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesundheit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Was genau ist Helicobacter pylori? - ASSSA Deutsch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Was genau ist Helicobacter pylori? - ASSSA Deutsch\" \/>\n<meta property=\"og:description\" content=\"Der menschliche Magen stellt ein sehr feindliches Milieu f&uuml;r jeden Mikroorganismus dar. Um die Verdauung der Nahrungsmittel vorzunehmen, sondert er gro&szlig;e Mengen Salzs&auml;ure ab, sodass der pH-Wert in der Regel unter 2 liegt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/\" \/>\n<meta property=\"og:site_name\" content=\"ASSSA Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-17T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-18T12:46:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asssa.es\/wp-content\/uploads\/2019\/08\/00184_1-9.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"297\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"soporte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"soporte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/was-genau-ist-helicobacter-pylori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/was-genau-ist-helicobacter-pylori\\\/\"},\"author\":{\"name\":\"soporte\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/e545c5b8d121593dd020f3a63aec3e90\"},\"headline\":\"Was genau ist Helicobacter pylori?\",\"datePublished\":\"2018-10-17T07:00:00+00:00\",\"dateModified\":\"2019-10-18T12:46:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/was-genau-ist-helicobacter-pylori\\\/\"},\"wordCount\":897,\"image\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/was-genau-ist-helicobacter-pylori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/00184_1-9.png\",\"articleSection\":[\"Gesundheit\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/was-genau-ist-helicobacter-pylori\\\/\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/was-genau-ist-helicobacter-pylori\\\/\",\"name\":\"Was genau ist Helicobacter pylori? - ASSSA Deutsch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/was-genau-ist-helicobacter-pylori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/was-genau-ist-helicobacter-pylori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/00184_1-9.png\",\"datePublished\":\"2018-10-17T07:00:00+00:00\",\"dateModified\":\"2019-10-18T12:46:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/e545c5b8d121593dd020f3a63aec3e90\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/was-genau-ist-helicobacter-pylori\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/was-genau-ist-helicobacter-pylori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/was-genau-ist-helicobacter-pylori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/00184_1-9.png\",\"contentUrl\":\"https:\\\/\\\/www.asssa.es\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/00184_1-9.png\",\"width\":600,\"height\":297},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/was-genau-ist-helicobacter-pylori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Was genau ist Helicobacter pylori?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/\",\"name\":\"ASSSA Deutsch\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/#\\\/schema\\\/person\\\/e545c5b8d121593dd020f3a63aec3e90\",\"name\":\"soporte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60bd01119ff87b83a195933bed289df0b2880b9446899bac13d38348f3c7a7f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60bd01119ff87b83a195933bed289df0b2880b9446899bac13d38348f3c7a7f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60bd01119ff87b83a195933bed289df0b2880b9446899bac13d38348f3c7a7f6?s=96&d=mm&r=g\",\"caption\":\"soporte\"},\"url\":\"https:\\\/\\\/www.asssa.es\\\/de\\\/blog-eintrag\\\/author\\\/soporte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Was genau ist Helicobacter pylori? - ASSSA Deutsch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/","og_locale":"de_DE","og_type":"article","og_title":"Was genau ist Helicobacter pylori? - ASSSA Deutsch","og_description":"Der menschliche Magen stellt ein sehr feindliches Milieu f&uuml;r jeden Mikroorganismus dar. Um die Verdauung der Nahrungsmittel vorzunehmen, sondert er gro&szlig;e Mengen Salzs&auml;ure ab, sodass der pH-Wert in der Regel unter 2 liegt.","og_url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/","og_site_name":"ASSSA Deutsch","article_published_time":"2018-10-17T07:00:00+00:00","article_modified_time":"2019-10-18T12:46:16+00:00","og_image":[{"width":600,"height":297,"url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2019\/08\/00184_1-9.png","type":"image\/png"}],"author":"soporte","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"soporte","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/#article","isPartOf":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/"},"author":{"name":"soporte","@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/e545c5b8d121593dd020f3a63aec3e90"},"headline":"Was genau ist Helicobacter pylori?","datePublished":"2018-10-17T07:00:00+00:00","dateModified":"2019-10-18T12:46:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/"},"wordCount":897,"image":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2019\/08\/00184_1-9.png","articleSection":["Gesundheit"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/","url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/","name":"Was genau ist Helicobacter pylori? - ASSSA Deutsch","isPartOf":{"@id":"https:\/\/www.asssa.es\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/#primaryimage"},"image":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2019\/08\/00184_1-9.png","datePublished":"2018-10-17T07:00:00+00:00","dateModified":"2019-10-18T12:46:16+00:00","author":{"@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/e545c5b8d121593dd020f3a63aec3e90"},"breadcrumb":{"@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/#primaryimage","url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2019\/08\/00184_1-9.png","contentUrl":"https:\/\/www.asssa.es\/wp-content\/uploads\/2019\/08\/00184_1-9.png","width":600,"height":297},{"@type":"BreadcrumbList","@id":"https:\/\/www.asssa.es\/de\/blog-eintrag\/was-genau-ist-helicobacter-pylori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asssa.es\/de\/"},{"@type":"ListItem","position":2,"name":"Was genau ist Helicobacter pylori?"}]},{"@type":"WebSite","@id":"https:\/\/www.asssa.es\/de\/#website","url":"https:\/\/www.asssa.es\/de\/","name":"ASSSA Deutsch","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asssa.es\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.asssa.es\/de\/#\/schema\/person\/e545c5b8d121593dd020f3a63aec3e90","name":"soporte","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/60bd01119ff87b83a195933bed289df0b2880b9446899bac13d38348f3c7a7f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/60bd01119ff87b83a195933bed289df0b2880b9446899bac13d38348f3c7a7f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/60bd01119ff87b83a195933bed289df0b2880b9446899bac13d38348f3c7a7f6?s=96&d=mm&r=g","caption":"soporte"},"url":"https:\/\/www.asssa.es\/de\/blog-eintrag\/author\/soporte\/"}]}},"jetpack_featured_media_url":"https:\/\/www.asssa.es\/wp-content\/uploads\/2019\/08\/00184_1-9.png","_links":{"self":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/4707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/comments?post=4707"}],"version-history":[{"count":1,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/4707\/revisions"}],"predecessor-version":[{"id":6197,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/posts\/4707\/revisions\/6197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/media\/4708"}],"wp:attachment":[{"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/media?parent=4707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/categories?post=4707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asssa.es\/de\/wp-json\/wp\/v2\/tags?post=4707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}